{"id":2249,"date":"2021-02-01T12:08:52","date_gmt":"2021-02-01T12:08:52","guid":{"rendered":"http:\/\/memoria.cepymearagon.es\/?page_id=2249"},"modified":"2021-03-24T16:27:06","modified_gmt":"2021-03-24T16:27:06","slug":"2020-civil-mercantil","status":"publish","type":"page","link":"https:\/\/memoria.cepymearagon.es\/index.php\/2020-civil-mercantil\/","title":{"rendered":"2020 Civil mercantil"},"content":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb css=\u00bb.vc_custom_1610018044125{margin-right: 5px !important;margin-left: 5px !important;}\u00bb][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb10&#8243;][vc_single_image image=\u00bb28&#8243; img_size=\u00bb\u00bb onclick=\u00bbcustom_link\u00bb qode_css_animation=\u00bb\u00bb link=\u00bbhttp:\/\/memoria.cepymearagon.es\/index.php\/2020-2\/\u00bb][\/vc_column][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb30&#8243;][custom_font font_size=\u00bb15&#8243; line_height=\u00bb26&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb300&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbno\u00bb border_color=\u00bb#114733&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/memoria.cepymearagon.es\/index.php\/2020-nuestra-organizacion\/\">Nuestra organizaci\u00f3n<\/a><\/h3>\n<p>[\/custom_font][\/vc_column][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb30&#8243;][custom_font font_size=\u00bb15&#8243; line_height=\u00bb26&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb300&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbno\u00bb border_color=\u00bb#114733&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/memoria.cepymearagon.es\/index.php\/2020-nuestros-servicios\/\">Nuestros servicios<\/a><\/h3>\n<p>[\/custom_font][\/vc_column][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb30&#8243;][custom_font font_size=\u00bb15&#8243; line_height=\u00bb26&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb300&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbno\u00bb border_color=\u00bb#114733&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/memoria.cepymearagon.es\/index.php\/2020-actividades\/\">Actividades<\/a><\/h3>\n<p>[\/custom_font][\/vc_column][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb20&#8243;][custom_font font_size=\u00bb15&#8243; line_height=\u00bb26&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb300&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbno\u00bb border_color=\u00bb#114733&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/memoria.cepymearagon.es\/index.php\/2020-rsa\/\">Responsabilidad Social Empresarial<\/a><\/h3>\n<p>[\/custom_font][\/vc_column][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb20&#8243;][custom_font font_size=\u00bb15&#8243; line_height=\u00bb26&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb300&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbno\u00bb border_color=\u00bb#114733&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/memoria.cepymearagon.es\/index.php\/2020-confederaciones-provinciales\/\">Confederaciones provinciales<\/a><\/h3>\n<p>[\/custom_font][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb10&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][image_with_text_over icon_size=\u00bbfa-lg\u00bb title_size=\u00bb50&#8243; title=\u00bbCIVIL MERCANTIL\u00bb image=\u00bb2464&#8243;][\/image_with_text_over][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][custom_font font_size=\u00bb30&#8243; line_height=\u00bb15&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb600&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbyes\u00bb color=\u00bb#114733&#8243;]<\/p>\n<p style=\"text-align: center;\">ACTUACIONES<\/p>\n<p>[\/custom_font][vc_empty_space height=\u00bb15&#8243;][vc_separator type=\u00bbnormal\u00bb][vc_empty_space][vc_column_text]Al igual que en anteriores ejercicios, y en cumplimiento del contenido y compromisos de la Carta de Servicios, la Asesor\u00eda Jur\u00eddica ha venido desarrollando en el a\u00f1o 2019 y para la Confederaci\u00f3n las funciones habituales de informaci\u00f3n, asistencia y asesoramiento en las \u00e1reas que le son propias, a solicitud de las empresas asociadas y sus componentes, bien de forma individual o colectiva.<\/p>\n<p>&nbsp;<\/p>\n<p>En concreto, se han seguido realizado las siguientes prestaciones de servicios:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Informaci\u00f3n legislativa, con notificaci\u00f3n de las novedades normativas con trascendencia en \u00e1reas civil, mercantil, fiscal y administrativa, tanto en el \u00e1mbito interno de CEPYME como a sus asociados.<\/li>\n<li>Emisi\u00f3n de dict\u00e1menes e informes, sobre novedades legislativas o materias de inter\u00e9s para los asociados, en especial mediante el uso de las noticias publicadas la p\u00e1gina web de la Confederaci\u00f3n.<\/li>\n<li>Formulaci\u00f3n de observaciones y alegaciones ante la Administraci\u00f3n en relaci\u00f3n a proyectos normativos.<\/li>\n<li>Participaci\u00f3n, como componentes, en Tribunales auton\u00f3micos y locales de consumo, mediaci\u00f3n y arbitraje.<\/li>\n<li>Participaci\u00f3n, como componentes, en Organismos del Gobierno de Arag\u00f3n (Comisi\u00f3n de Precios, Consejo Aragon\u00e9s del Consumo, Foro de la contrataci\u00f3n, etc.)<\/li>\n<li>Asistencia y participaci\u00f3n en convocatorias, foros y reuniones p\u00fablicas convocadas por la Administraci\u00f3n (consumo, etc.)<\/li>\n<li>Asesoramiento en materia contractual:\n<ul>\n<li>Informaci\u00f3n y asesoramiento en relaciones mercantiles de todo tipo.<\/li>\n<li>Redacci\u00f3n de contratos y convenios.<\/li>\n<li>Constituci\u00f3n, modificaci\u00f3n y disoluci\u00f3n de entidades y sociedades mercantiles<\/li>\n<\/ul>\n<\/li>\n<li>Informaci\u00f3n y asesoramiento en aspectos jur\u00eddicos relevantes para la puesta en marcha, alta y legalizaci\u00f3n de actividades empresariales.<\/li>\n<li>Formulaci\u00f3n e impugnaci\u00f3n de recursos y sanciones administrativas.<\/li>\n<li>Resoluci\u00f3n, por v\u00eda transaccional o judicial, de reclamaciones de cantidad, aplicaci\u00f3n o interpretaci\u00f3n contractual o reclamaci\u00f3n en materia de garant\u00edas o de consumo.<\/li>\n<li>Informaci\u00f3n sobre gestiones de \u00edndole personal, como herencias, capitulaciones matrimoniales, etc.<\/li>\n<li>Consultas verbales, telef\u00f3nicas, por correo electr\u00f3nico y presenciales.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb90&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][custom_font font_size=\u00bb30&#8243; line_height=\u00bb15&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb600&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbyes\u00bb color=\u00bb#114733&#8243;]<\/p>\n<p style=\"text-align: center;\">MATERIAS DESTACADAS<\/p>\n<p>[\/custom_font][vc_empty_space height=\u00bb15&#8243;][vc_separator type=\u00bbnormal\u00bb][vc_empty_space][vc_column_text]Como todos los ejercicios, y con motivo de elaboraci\u00f3n de la presente memoria, destacamos las materias que han supuesto una mayor incidencia en n\u00famero de consultas o intervenciones para esta Asesor\u00eda:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Reclamaciones de cantidad por impago<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Rompi\u00e9ndose lo que ha sido una l\u00ednea de disminuci\u00f3n en tal materia en anteriores ejercicios, y en especial el segundo semestre del a\u00f1o, se ha producido un evidente incremento en solicitud de informaci\u00f3n y modelos para reclamaciones extrajudiciales de cantidad y el posterior el planteamiento del procedimiento judicial Monitorio de reclamaci\u00f3n de cantidad, si bien es consulta habitual en la Asesor\u00eda.<\/p>\n<p>Como se destaca todos los a\u00f1os, la actuaci\u00f3n en este \u00e1mbito de reclamaciones es doble: buscar soluci\u00f3n al puntual incumplimiento contractual por parte del acreedor, as\u00ed como animar a las distintas Asociaciones y sus componentes a adoptar h\u00e1bitos y protocolos de actuaci\u00f3n que favorezcan el cobro de tales cantidades y el cumplimiento de las obligaciones contractuales en general (redacci\u00f3n de contratos y presupuestos, justificaci\u00f3n documental de las intervenciones o actuaciones con los clientes, etc.) y es que, pese a la insistencia en tal tema, sigue siendo frecuente el comprobar que, ante situaciones de morosidad o impago, no se posee m\u00e1s documentaci\u00f3n acreditativa de la obra o servicio realizados que las facturas emitidas por el asociado, con la problem\u00e1tica que implica tal falta de prueba en reclamaciones judiciales o extrajudiciales.<\/p>\n<p>El porcentaje de \u00e9xito de acuerdos y transacciones extrajudiciales en reclamaci\u00f3n de cantidad sigue siendo escaso, por lo que se han promocionado entre los asociados formulas lo menos gravosas posibles para la reclamaci\u00f3n judicial de deudas. (Arbitrajes, Monitorios, etc)<\/p>\n<p>Las renegociaciones de cr\u00e9ditos y documentaci\u00f3n (reconocimientos) de deudas siguen siendo, como consecuencia de lo anteriormente expuesto, una materia de consulta habitual en la Asesor\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Acceso a pr\u00e9stamos y l\u00edneas de financiaci\u00f3n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La situaci\u00f3n derivada del COVID ha supuesto una quiebra en la pr\u00e1ctica habitual en tal materia (ver apartado COVID).<\/p>\n<p>Como en otros ejercicios, se han planteado consultas por casos de conversi\u00f3n de las l\u00edneas de cr\u00e9dito \u2013 a la hora de su renovaci\u00f3n &#8211; en pr\u00e9stamos personales con exigencia de gran n\u00famero de garant\u00edas o afianzamientos personales.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Garant\u00edas del consumidor \/ compraventa de bienes al consumo<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>No constituye novedad y se reitera como una de las materias fundamentales en la Asesor\u00eda ejercicio tras ejercicio, en especial lo referente a contenido y plazo de las mismas.<\/p>\n<p>Se reitera la obligaci\u00f3n legal de tenencia de Hojas de reclamaciones a disposici\u00f3n de los consumidores, en especial en actividades con atenci\u00f3n directa al p\u00fablico, recordando la necesidad de emplear el nuevo modelo existente, haciendo notar que el mismo incluye la opci\u00f3n de sumisi\u00f3n voluntaria a arbitraje.<\/p>\n<p>Como en otros ejercicios, por el Consejo Aragon\u00e9s de Consumo, y dada nuestra condici\u00f3n de vocales en tal instituci\u00f3n, se ha informado de las campa\u00f1as de inspecci\u00f3n en materia de Consumo han promovido, tanto en \u00e1mbito nacional como auton\u00f3mico, las autoridades de consumo, habi\u00e9ndose prestado colaboraci\u00f3n en labores de difusi\u00f3n de las mismas por medio de notificaci\u00f3n al efecto (circulares) a los Asociados.<br \/>\nSe destacan \u2013 por habituales \u2013 las campa\u00f1as generales de rebajas, precios, contrataci\u00f3n, etc. As\u00ed como las sectoriales (talleres, centros de est\u00e9tica, servicios financieros, etc). Las ventas por internet y el comercio electr\u00f3nico en general numerosas intervenciones de las autoridades de consumo (devoluciones, etc)<\/p>\n<p>Sin novedad, y al igual que indic\u00e1bamos en la Memoria del pasado ejercicio, siguen realiz\u00e1ndose intervenciones ante el Tribunal Arbitral de Consumo, como vocal \/ componente en representaci\u00f3n de las organizaciones empresariales. La intervenci\u00f3n ha descendido respecto a otros a\u00f1os dada la realizaci\u00f3n de convenios directos de las Asociaciones con el organismo de Consumo y que se traduce en la posibilidad de designaci\u00f3n de \u00e1rbitros por las mismas, haciendo menos necesaria la intervenci\u00f3n de la Confederaci\u00f3n. Es esta sede los temas fundamentalmente dilucidados y que afectan con frecuencia a asociados, se refieren a las siguientes materias (por orden de incidencia):<\/p>\n<ul>\n<li>Telefon\u00eda<\/li>\n<li>Servicios de suministro el\u00e9ctrico: facturaci\u00f3n y contrataci\u00f3n.<\/li>\n<li>Garant\u00edas de ventas de bienes al consumo: especialmente electrodom\u00e9sticos y ropa y vestidos.<\/li>\n<li>Reparaciones: electrodom\u00e9sticos, aparatos de telefon\u00eda y el\u00e9ctricos en general, as\u00ed como talleres de autom\u00f3vil<\/li>\n<li>Obras y servicios y reparaciones a domicilio: fontaner\u00eda, electricidad y otros.<\/li>\n<li>Venta de muebles<\/li>\n<\/ul>\n<p>Se promueve el empleo de f\u00f3rmulas contractuales de sumisi\u00f3n al arbitraje para la resoluci\u00f3n de conflictos de interpretaci\u00f3n y\/o aplicaci\u00f3n de las relaciones comerciales, habi\u00e9ndose comprobado igualmente no solo un incremento del n\u00famero de asuntos, sino tambi\u00e9n de la entidad econ\u00f3mica y jur\u00eddica de los mismos.<\/p>\n<p>Como datos estad\u00edsticos, y tal y como se hace constar en la informaci\u00f3n institucional de Consumo \u2013 sin novedad en relaci\u00f3n a anteriores ejercicios &#8211; el porcentaje de laudos favorables a los empresarios se sigue situando en una cifra media cercana (ligeramente inferior) al 50% de los emitidos, y de los mismos sigue desprendi\u00e9ndose normalmente la necesidad de recordar a los Asociados la necesidad de cumplir con la correcta y adecuada documentaci\u00f3n de las relaciones comerciales con los consumidores (contratos, presupuestos, etc.).<\/p>\n<p>Como aspecto negativo, se encuentra la sensaci\u00f3n, extendida en algunos sectores empresariales, de que las facilidad y gratuidad de los servicios de arbitraje de consumo pudiera promover en ocasiones la querulancia y uso abusivo de los mismos por los consumidores como f\u00f3rmula de obtenci\u00f3n de ventajas o beneficios en detrimento del empresario. Desde la Asesor\u00eda, se atienden y controlan los posibles casos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Comercio electr\u00f3nico<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La situaci\u00f3n actual ha supuesto un vuelco en tal materia. En este apartado hacemos referencia \u2013 en especial relaci\u00f3n con el apartado precedente \u2013 el incremento de situaciones de control (apertura de expedientes de inspecci\u00f3n, sancionadores, etc) por parte de AAPP <u>de otras CCAA<\/u> sobre p\u00e1ginas web de empresas domiciliadas en nuestra CA que ofrecen el servicio de venta o contrataci\u00f3n electr\u00f3nica. (Vg. Expediente sancionador abierto por la CA de Andaluc\u00eda contra una empresa aragonesa de venta de mobiliario que se publicita en internet, por entender que no publicita adecuadamente sus ofertas en rebajas)<\/p>\n<p>Sin perjuicio de la normativa vigente sobre comercio electr\u00f3nico, se est\u00e1 planteando con la Administraci\u00f3n la conveniencia de la determinaci\u00f3n de criterios competenciales adecuados en tal materia.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contrataci\u00f3n con la Administraci\u00f3n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Relacionado con esta materia, han sido frecuentes las gestiones y consultas en materias accesorias, como la del registro de subcontrataci\u00f3n y la inscripci\u00f3n de empresas licitantes en los registros p\u00fablicos al efecto, as\u00ed como las garant\u00edas de cobro por el subcontratado y la posibilidad del ejercicio de la acci\u00f3n directa contra la administraci\u00f3n en caso de impago del contratista.<\/p>\n<p>La reciente entrada en vigor de la nueva normativa de contrataci\u00f3n p\u00fablica (<u>Ley 9\/2017, de 8 de noviembre, de Contratos del Sector P\u00fablico<\/u>), sigue planteando consultas en su aplicaci\u00f3n, en especial las derivadas de los contratos de menor entidad, reflejo del nuevo criterio legal de priorizaci\u00f3n en la formaci\u00f3n de lotes contractuales para permitir el acceso a Pymes: calificaci\u00f3n o no de los licitantes, pliegos con exigencias t\u00e9cnicas o de producto determinado, problemas de valoraci\u00f3n por el abandono del criterio del precio, etc.<\/p>\n<p>Como en otros a\u00f1os se recuerda, por lo que de acceso a informaci\u00f3n de alto nivel y v\u00eda de planteamiento de consultas supone para las Asociaciones, la participaci\u00f3n de en la <u>Junta Consultiva de Contrataci\u00f3n Administrativa de Arag\u00f3n<\/u>: la Confederaci\u00f3n lleva ya tiempo participando en este organismo, pero debe recordarse nuevamente \u2013 en especial tras las \u00faltimas novedades legislativas habidas en el tema de contrataci\u00f3n p\u00fablica \u2013 que parte de la problem\u00e1tica habitual de la contrataci\u00f3n (conflictos interpretativos o de aplicaci\u00f3n o pliegos o contratos p\u00fablicos, reclamaciones o consultas) pueden tener un cauce de soluci\u00f3n a trav\u00e9s de la solicitud de informes o recomendaciones a la citada Junta Consultiva o, mediante el planteamiento de recursos ante el Tribunal Administrativo de Contratos P\u00fablicos de Arag\u00f3n. (TAPCA \u2013 Recurso especial en materia de contrataci\u00f3n)<\/p>\n<p>Hablamos en su d\u00eda de la constituci\u00f3n, el 19 de septiembre de 2017, del <u>Foro de Contratos P\u00fablicos de la CA de Arag\u00f3n<\/u>, creado para complementar a la Junta Consultiva y con la intenci\u00f3n de ejercer foro de debate y recepci\u00f3n de los intereses de los distintos agentes sociales y la administraci\u00f3n en el uso de la herramienta de planificaci\u00f3n econ\u00f3mica que constituye la contrataci\u00f3n p\u00fablica en general. No es tanto un \u00f3rgano de car\u00e1cter t\u00e9cnico sino de comunicaci\u00f3n e intercambio de los intereses de los agentes que participan en la contrataci\u00f3n, todo ello en l\u00ednea de la nueva legislaci\u00f3n sobre la materia. <u>Sin embargo<\/u>, tras unas primeras reuniones en las que esta entidad particip\u00f3 activamente, <u>no se ha recibido ninguna nueva citaci\u00f3n para continuar con sus actividades, no previ\u00e9ndose futuras convocatorias en tal organismo.<\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><strong>Asociaciones<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Sigue prest\u00e1ndose colaboraci\u00f3n a las mismas, habi\u00e9ndose \u2013 a diferencia de otros ejercicios \u2013 producido un incremento en las consultas e intervenciones en la creaci\u00f3n de nuevas asociaciones (consultas en tal sentido) habidas en ejercicios anteriores.<\/p>\n<ul>\n<li>V\u00e9ase lo que se indica en el apartado de requerimientos y campa\u00f1as de la Administraci\u00f3n.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Protecci\u00f3n de Datos de car\u00e1cter Personal<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Se siguen planteado consultas al efecto, muchas veces motivadas por campa\u00f1as de marketing muy agresivas llevadas a cabo por empresas dedicadas a prestar servicios en tal materia y que motivan dudas en los asociados.<\/p>\n<p>Se insiste \u2013 tanto en el \u00e1mbito interno de la Confederaci\u00f3n como con sus asociados \u2013 en la importancia del cumplimiento de esta normativa, con advertencia de las sanciones previstas para el caso de incumplimiento y la peligrosidad que supone el no cumplimiento de los \u2013 sencillos \u2013 tr\u00e1mites legales previstos,<\/p>\n<p>Se mantienen las consultas de los Asociados sobre tal materia, en especial sobre los llamados \u201clistados de morosidad\u201d, habi\u00e9ndose recordado en varias ocasiones las limitaciones legales para su uso, tanto por la normativa de protecci\u00f3n de la competencia, como por la propia de datos de car\u00e1cter personal.<\/p>\n<p>La novedad este ejercicio vino marcada por la entrada en vigor del Reglamento General de Protecci\u00f3n de Datos (RGPD), as\u00ed como la publicaci\u00f3n posterior de la nueva Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales que ha exigido a las empresas \u2013 en un proceso que continua en la actualidad \u2013 un necesario proceso de adaptaci\u00f3n, con abandono del anterior sistema de registro de las bases de datos.<\/p>\n<p>Se sigue promocionando el uso de la herramienta inform\u00e1tica FACILITA, que se encuentra en la p\u00e1gina web de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, para realizar el alta y dar cumplimiento a gran parte de las exigencias legales en tal materia para PYMES y aut\u00f3nomos, habi\u00e9ndose realizado un elevado n\u00famero de charlas, exposiciones y jornadas en asociaciones (no solo de la FEMZ y en Zaragoza, sino en otras localidades), explicando el contenido de la reforma.<\/p>\n<p>Se siguen planteando gran n\u00famero de peticiones de intervenci\u00f3n de esta Asesor\u00eda (derivadas en ocasiones al \u00e1rea de la Asesor\u00eda Laboral) para <u>supuestos de transmisi\u00f3n y\/o sucesi\u00f3n de peque\u00f1as empresas<\/u>, de car\u00e1cter familiar, tanto a familiares, como a empleados o terceros, con ramificaciones en los temas fiscales, laborales (sucesi\u00f3n de plantillas, etc). Muchas de las consultas se deben a las manifiestas dificultades de las empresas de mantener la actividad dentro de umbrales de rentabilidad admisibles, que llevan a provocar el adelantamiento de las situaciones de cierre o jubilaci\u00f3n. Muchas de las consultas han venido motivadas, a su vez, por el cambio de la normativa laboral en materia de jubilaci\u00f3n o prolongaci\u00f3n de la vida laboral (jubilaci\u00f3n activa o parcial, etc).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fiscalidad<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>El <u>tratamiento fiscal<\/u> en Arag\u00f3n de las sucesiones de empresa \u2013 en especial en supuesto de donaciones o sucesiones \u2013 ha planteado igualmente alguna consulta.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Campa\u00f1as de inspecci\u00f3n y\/o requerimientos de la Administraci\u00f3n:<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s de las habituales (y anunciadas con antelaci\u00f3n) campa\u00f1as de Consumo y de las de car\u00e1cter fiscal, no han sido relevantes las consultas sobre tales materias.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mecanismo de segunda oportunidad, reducci\u00f3n de la carga financiera y otras medidas de orden social<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Se hace referencia a esta materia \u2013 al igual que en ejercicios anteriores &#8211; por lo que de llamativo tiene la escasa repercusi\u00f3n en lo que a consultas o intervenciones de esta Asesoria ha tenido una norma (Ley 25\/2015, de 28 de julio) de especial trascendencia en situaciones de iliquidez o insolvencia. El escaso uso de tal herramienta legal, viene pareja al descenso de situaciones de concurso.<\/p>\n<p>(Ver apartado COVID, en relaci\u00f3n a las reformas de la normativa concursal en el a\u00f1oso 2020)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Reclamaciones entidades financieras \/ Cl\u00e1usula suelo y otras<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La cierta \u201cautomatizaci\u00f3n\u201d que se ha alcanzado \u2013 tras recientes fallos judiciales \u2013 en la tal materia, ha hecho que sean marginales las consultas que ha habido en la asesor\u00eda en tal materia<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Administraci\u00f3n Electr\u00f3nica<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Durante el a\u00f1o 2020 (al igual que en ejercicios anteriores) se ha reiterado constantemente entre los asociados, y no \u00fanicamente entre los asociados personas jur\u00eddicas (\u00fanicos obligados de momento), la importancia de no quedar rezagados en tal materia, evitando en lo posible la llamada \u201cbrecha digital\u201d en la relaci\u00f3n con las Administraci\u00f3n y con otras entidades, fomentando la obtenci\u00f3n y uso del certificado digital (firma electr\u00f3nica) como instrumento preferente de relaci\u00f3n con la Administraci\u00f3n. Las Leyes 39\/2015, de procedimiento administrativo com\u00fan y 40\/2015, de r\u00e9gimen jur\u00eddico del sector p\u00fablico afecta en especial las que adoptan formas de persona jur\u00eddica, con la imposici\u00f3n de la forma de comunicaci\u00f3n electr\u00f3nica como \u00fanica posible con las AAPP, adem\u00e1s de otras novedades de gran calado (registro de apoderamientos, etc)<\/p>\n<p>Las que reproch\u00e1bamos como carencias de las propias AAPP (en especial la Auton\u00f3mica) que dificultaban el uso de la Administraci\u00f3n Electr\u00f3nica, creando normalmente situaciones de inseguridad jur\u00eddica al convivir con formas de actuaci\u00f3n o realizaci\u00f3n de tr\u00e1mites \u201cf\u00edsicos\u201d (registros, etc ) en teor\u00eda ya no autorizados, van paulatinamente corrigi\u00e9ndose. (V\u00e9anse en todo caso, los comentarios que, al respecto, realizamos en el apartado COVID)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cNuevos empresarios\u201d<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ha ido en aumento \u2013 en especial desde el final de verano y prolong\u00e1ndose en el 2020 \u2013 las consultas de j\u00f3venes <u>no asociados<\/u> sobre tramites y consejos para el inicio de muy diversos tipos de actividad empresarial, que en numerosas ocasiones acuden a nuestra asesor\u00eda por remisi\u00f3n expresa de las AAPP, como nos comentan. Las entrevistas presenciales se han complementado con el suministro de fuentes de informaci\u00f3n de las AAPP y ayudas para tales casos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Otras materias: (Normativa):<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Con la l\u00f3gica excepci\u00f3n de la normativa COVID (derivada de la situaci\u00f3n de alarma y pandemia) que ha supuesto una avalancha normativa de escasa calidad t\u00e9cnica y dif\u00edcil seguimiento (ver apartado COVID), ha sido notable el descenso de la actividad normativa, dada la situaci\u00f3n pol\u00edtica vivida en el a\u00f1o 2020.[\/vc_column_text][vc_empty_space height=\u00bb90&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][custom_font font_size=\u00bb30&#8243; line_height=\u00bb15&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb600&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbyes\u00bb color=\u00bb#114733&#8243;]<\/p>\n<p style=\"text-align: center;\">COVID Y ESTADO DE ALARMA<\/p>\n<p>[\/custom_font][vc_empty_space height=\u00bb15&#8243;][vc_separator type=\u00bbnormal\u00bb][vc_empty_space][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner][vc_column_text]Abrimos un apartado especial por la situaci\u00f3n de car\u00e1cter excepcional que ha afectado a la pr\u00e1ctica totalidad del ejercicio 2020, destac\u00e1ndose en este apartado, que esperamos temporal:<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Actividad legislativa<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>No se puede calificar la actividad del legislador (tanto estatal como auton\u00f3mico) sino como <u>ca\u00f3tica<\/u>. La avalancha diaria de normas de toda clase, todas ellas con la nota de urgencia y con el denominador com\u00fan de una escasa calidad de t\u00e9cnica normativa, de dif\u00edcil cuando no imposible concordancia con las normas existentes y entre s\u00ed, promulgadas muchas de ellas a escasas horas de su entrada en vigor, ha supuesto un esfuerzo enorme a esta y otras asesor\u00edas departamentos de la entidad, que ha llevado a cabo un esfuerzo enorme de informaci\u00f3n y difusi\u00f3n de las novedades normativas de transcendencia en la actividad empresarial. Nos remitimos al respecto al contenido y n\u00famero de circulares informativas publicadas en la p\u00e1gina web.<\/p>\n<p>Las consultas con las propias AAPP, en solicitud de criterios oficiales sobre muchas materias (desplazamientos, medios de transporte, actividades permitidas \u2026) fueron habituales a fin de evitar en lo posible el ambiente de elevada inseguridad jur\u00eddica para el empresario y su actividad, provocada muchas de las veces por el propio legislador.<\/p>\n<p>No ha ayudado en este tema la distribuci\u00f3n competencial entre estado y comunidad aut\u00f3noma.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Consultas<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Las consultas \u2013 en materia COVID \u2013 han sido muy numerosas, provocadas muchas de ellas por la citada actividad normativa y lo excepciona de la situaci\u00f3n.<\/p>\n<p>Materias:<\/p>\n<ul>\n<li>alcance y l\u00edmite de la situaci\u00f3n de alarma,<\/li>\n<li>prohibiciones de actividad,<\/li>\n<li>desplazamientos,<\/li>\n<li>permisos y declaraciones responsables<\/li>\n<li>requisitos y medidas sanitarias y de prevenci\u00f3n<\/li>\n<li>consecuencias laborales (ERTES, cotizaci\u00f3n, teletrabajo, etc)<\/li>\n<li>etc<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Normativa concursal \u2013 Insolvencias<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>La situaci\u00f3n derivada de la pandemia ha tenido como consecuencia normativa de especial importancia en este apartado la suspensi\u00f3n del perentorio (y breve) plazo de dos meses para que el empresario promueva el expediente (concurso voluntario o, en su caso, el preconcurso) ante el juzgado de lo Mercantil. En la actualidad tal aplazamiento sigue en vigor, pero han sido numerosas las consultas en tal sentido, previ\u00e9ndose un elevado n\u00famero de expedientes a finalizaci\u00f3n de la<em> vacatio<\/em> legal en vigor.<\/p>\n<p>Se sigue en la asesor\u00eda recordando la normativa de la \u201csegunda oportunidad\u201d y su reivindicaci\u00f3n de uso en tales momentos.<\/p>\n<p>Resulta notorio el n\u00famero de casos en los que se anuncia por el empresario bien un adelanto de la situaci\u00f3n de jubilaci\u00f3n que legalmente proceder\u00eda, bien el anuncio de que no se va a continuar con la actividad por sus hijos o familiares colaboradores.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fiscalidad \u2013 Aplazamientos<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Como ha habido que indicar en las muchas consultas al respecto, no ha habido condonaciones, sino aplazamientos. La carga fiscal se ha pospuesto, pero no eliminado o reducido.<\/p>\n<p>Al respecto, el cobro de una sola vez y sin preaviso de tales cantidades aplazadas por la AEAT (vg. principios de junio del 2020), provoc\u00f3 numerosas consultas y muy graves situaciones de iliquidez en muchas empresas.<\/p>\n<p>Las sanciones y cobro de intereses de demora por la AEAT has sido el resultado, con elevado n\u00famero de consultas en tales materias.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Administraci\u00f3n electr\u00f3nica &#8211; Relaci\u00f3n con las AAPP<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Ha sido esta materia una de las que ha puesto de manifiesto una no muy adecuada adaptaci\u00f3n por parte de la administraci\u00f3n al criterio de <u>no presencialidad<\/u> en su actividad, provocando un elevado n\u00famero de consultas y quejas.<\/p>\n<p>El sistema de <u>cita previa<\/u> \u2013 con plazos claramente inaceptables en algunos casos y con car\u00e1cter no suspensivo de los plazos \u2013 ha provocado situaciones de tramitaci\u00f3n administrativa de dif\u00edcil soluci\u00f3n, que se ha agravado con la ahora apremiante necesidad (recordamos al efecto nuestra insistencia desde hace a\u00f1os en tal materia) de la tenencia de <u>firma o certificado electr\u00f3nico<\/u> para la realizaci\u00f3n de gestiones de cualquier clase con las AAPP. Las consultas sobre la forma y medios de obtenci\u00f3n de tal firma, junto con las novedades normativas en tal materia, han sido \u2013 y siguen siendo \u2013 habituales en la asesor\u00eda.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb90&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][custom_font font_size=\u00bb30&#8243; line_height=\u00bb15&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb600&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbyes\u00bb color=\u00bb#114733&#8243;]<\/p>\n<p style=\"text-align: center;\">NORMATIVA DESTACADA<\/p>\n<p>[\/custom_font][vc_empty_space height=\u00bb15&#8243;][vc_separator type=\u00bbnormal\u00bb][vc_empty_space][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner][vc_column_text]<\/p>\n<div class=\"wpb_tabstabs_holder clearfix\" data-interval=\"0\">\n<div class=\"q_tabs horizontal left\">\n<div class=\"tabs-container\">\n<div id=\"tab-1616514746230-3-3\" class=\"tab-content\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Como normas destacables \u2013 por su trascendencia pr\u00e1ctica fundamentalmente en lo que a este Servicio interesa y al margen de otras de innegable importancia pol\u00edtica o social \u2013 se mencionan entre otras (no incluy\u00e9ndose las normas derogadas):<\/p>\n<p>&nbsp;<\/p>\n<h3>LEYES ORG\u00c1NICAS<\/h3>\n<p>&nbsp;<\/p>\n<p>Org\u00e1nica 3\/2020, de 29 de diciembre, por la que se modifica la Ley Org\u00e1nica 2\/2006, de 3 de mayo, de Educaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<h3>LEYES<\/h3>\n<p>&nbsp;<\/p>\n<ul>\n<li>Ley 3\/2020, de 18 de septiembre, de medidas procesales y organizativas para hacer frente al COVID-19 en el \u00e1mbito de la Administraci\u00f3n de Justicia.<\/li>\n<li>Ley 1\/2020, de 15 de julio, por la que se deroga el despido objetivo por faltas de asistencia al trabajo establecido en el art\u00edculo 52.d) del texto refundido de la Ley del Estatuto de los Trabajadores, aprobado por el Real Decreto Legislativo 2\/2015, de 23 de octubre.<\/li>\n<li>Ley 2\/2020, de 27 de julio, por la que se modifica el art\u00edculo 324 de la Ley de Enjuiciamiento Criminal.<\/li>\n<li>Ley 4\/2020, de 15 de octubre, del Impuesto sobre Determinados Servicios Digitales.<\/li>\n<li>Ley 5\/2020, de 15 de octubre, del Impuesto sobre las Transacciones Financieras.<\/li>\n<li>Ley 6\/2020, de 11 de noviembre, reguladora de determinados aspectos de los servicios electr\u00f3nicos de confianza.<\/li>\n<li>Ley 7\/2020, de 13 de noviembre, para la transformaci\u00f3n digital del sistema financiero.<\/li>\n<li>Ley 8\/2020, de 16 de diciembre, por la que se adoptan determinadas medidas urgentes en materia de agricultura y alimentaci\u00f3n.<\/li>\n<li>Ley 9\/2020, de 16 de diciembre, por la que se modifica la Ley 1\/2005, de 9 de marzo, por la que se regula el r\u00e9gimen del comercio de derechos de emisi\u00f3n de gases de efecto invernadero, para intensificar las reducciones de emisiones de forma eficaz en relaci\u00f3n con los costes.<\/li>\n<li>Ley 10\/2020, de 29 de diciembre, por la que se modifica la Ley 58\/2003, de 17 de diciembre, General Tributaria, en transposici\u00f3n de la Directiva (UE) 2018\/822 del Consejo, de 25 de mayo de 2018, que modifica la Directiva 2011\/16\/UE por lo que se refiere al intercambio autom\u00e1tico y obligatorio de informaci\u00f3n en el \u00e1mbito de la fiscalidad en relaci\u00f3n con los mecanismos transfronterizos sujetos a comunicaci\u00f3n de informaci\u00f3n.<\/li>\n<li>Ley 11\/2020, de 30 de diciembre, de Presupuestos Generales del Estado para el a\u00f1o 2021.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>LEYES ARAG\u00d3N<\/h3>\n<p>&nbsp;<\/p>\n<ul>\n<li>Ley 10\/2019, de 30 de diciembre, de Presupuestos de la Comunidad Aut\u00f3noma de Arag\u00f3n para el ejercicio 2020.<\/li>\n<li>Ley 1\/2020, de 9 de julio, por la que se establecen medidas excepcionales para el ejercicio 2020 en determinados tributos gestionados por la Comunidad Aut\u00f3noma de Arag\u00f3n.<\/li>\n<li>Ley 2\/2020, de 22 de octubre, de Estad\u00edstica de Arag\u00f3n.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>DECRETOS LEYES<\/h3>\n<p>&nbsp;<\/p>\n<ul>\n<li>Real Decreto-ley 8\/2020, de 17 de marzo, de medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19.<\/li>\n<li>Real Decreto-ley 11\/2020, de 31 de marzo, por el que se adoptan medidas urgentes complementarias en el \u00e1mbito social y econ\u00f3mico para hacer frente al COVID-19.<\/li>\n<li>Real Decreto-ley 25\/2020, de 3 de julio, de medidas urgentes para apoyar la reactivaci\u00f3n econ\u00f3mica y el empleo.<\/li>\n<li>Real Decreto-ley 9\/2020, de 27 de marzo, por el que se adoptan medidas complementarias, en el \u00e1mbito laboral, para paliar los efectos derivados del COVID-19.<\/li>\n<li>Real Decreto-ley 15\/2020, de 21 de abril, de medidas urgentes complementarias para apoyar la econom\u00eda y el empleo.<\/li>\n<li>Real Decreto-ley 17\/2020, de 5 de mayo, por el que se aprueban medidas de apoyo al sector cultural y de car\u00e1cter tributario para hacer frente al impacto econ\u00f3mico y social del COVID-2019.<\/li>\n<li>Real Decreto-ley 20\/2020, de 29 de mayo, por el que se establece el ingreso m\u00ednimo vital.<\/li>\n<li>Real Decreto-ley 6\/2020, de 10 de marzo, por el que se adoptan determinadas medidas urgentes en el \u00e1mbito econ\u00f3mico y para la protecci\u00f3n de la salud p\u00fablica.<\/li>\n<li>Real Decreto-ley 7\/2020, de 12 de marzo, por el que se adoptan medidas urgentes para responder al impacto econ\u00f3mico del COVID-19.<\/li>\n<li>Real Decreto-ley 10\/2020, de 29 de marzo, por el que se regula un permiso retribuido recuperable para las personas trabajadoras por cuenta ajena que no presten servicios esenciales, con el fin de reducir la movilidad de la poblaci\u00f3n en el contexto de la lucha contra el COVID-19.<\/li>\n<li>Real Decreto-ley 13\/2020, de 7 de abril, por el que se adoptan determinadas medidas urgentes en materia de empleo agrario.<\/li>\n<li>Real Decreto-ley 19\/2020, de 26 de mayo, por el que se adoptan medidas complementarias en materia agraria, cient\u00edfica, econ\u00f3mica, de empleo y Seguridad Social y tributarias para paliar los efectos del COVID-19.<\/li>\n<li>Real Decreto-ley 21\/2020, de 9 de junio, de medidas urgentes de prevenci\u00f3n, contenci\u00f3n y coordinaci\u00f3n para hacer frente a la crisis sanitaria ocasionada por el COVID-19.<\/li>\n<li>Real Decreto-ley 22\/2020, de 16 de junio, por el que se regula la creaci\u00f3n del Fondo COVID-19 y se establecen las reglas relativas a su distribuci\u00f3n y libramiento.<\/li>\n<li>Real Decreto-ley 23\/2020, de 23 de junio, por el que se aprueban medidas en materia de energ\u00eda y en otros \u00e1mbitos para la reactivaci\u00f3n econ\u00f3mica.<\/li>\n<li>Real Decreto-ley 24\/2020, de 26 de junio, de medidas sociales de reactivaci\u00f3n del empleo y protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad del sector industrial.<\/li>\n<li>Real Decreto-ley 26\/2020, de 7 de julio, de medidas de reactivaci\u00f3n econ\u00f3mica para hacer frente al impacto del COVID-19 en los \u00e1mbitos de transportes y vivienda.<\/li>\n<li>Real Decreto-ley 30\/2020, de 29 de septiembre, de medidas sociales en defensa del empleo.<\/li>\n<li>Real Decreto-ley 32\/2020, de 3 de noviembre, por el que se aprueban medidas sociales complementarias para la protecci\u00f3n por desempleo y de apoyo al sector cultural.<\/li>\n<li>Real Decreto-ley 34\/2020, de 17 de noviembre, de medidas urgentes de apoyo a la solvencia empresarial y al sector energ\u00e9tico, y en materia tributaria.<\/li>\n<li>Real Decreto-ley 1\/2020, de 14 de enero, por el que se establece la revalorizaci\u00f3n y mantenimiento de las pensiones y prestaciones p\u00fablicas del sistema de Seguridad Social.<\/li>\n<li>Real Decreto-ley 2\/2020, de 21 de enero de 2020, por el que se aprueban medidas urgentes en materia de retribuciones en el \u00e1mbito del sector p\u00fablico.<\/li>\n<li>Real Decreto-ley 3\/2020, de 4 de febrero, de medidas urgentes por el que se incorporan al ordenamiento jur\u00eddico espa\u00f1ol diversas directivas de la Uni\u00f3n Europea en el \u00e1mbito de la contrataci\u00f3n p\u00fablica en determinados sectores; de seguros privados; de planes y fondos de pensiones; del \u00e1mbito tributario y de litigios fiscales.<\/li>\n<li>Real Decreto-ley 12\/2020, de 31 de marzo, de medidas urgentes en materia de protecci\u00f3n y asistencia a las v\u00edctimas de violencia de g\u00e9nero.<\/li>\n<li>Real Decreto-ley 14\/2020, de 14 de abril, por el que se extiende el plazo para la presentaci\u00f3n e ingreso de determinadas declaraciones y autoliquidaciones tributarias.<\/li>\n<li>Real Decreto-ley 18\/2020, de 12 de mayo, de medidas sociales en defensa del empleo.<\/li>\n<li>Real Decreto-ley 28\/2020, de 22 de septiembre, de trabajo a distancia.<\/li>\n<li>Real Decreto-ley 29\/2020, de 29 de septiembre, de medidas urgentes en materia de teletrabajo en las Administraciones P\u00fablicas y de recursos humanos en el Sistema Nacional de Salud para hacer frente a la crisis sanitaria ocasionada por la COVID-19.<\/li>\n<li>Real Decreto-ley 31\/2020, de 29 de septiembre, por el que se adoptan medidas urgentes en el \u00e1mbito de la educaci\u00f3n no universitaria.<\/li>\n<li>Real Decreto-ley 33\/2020, de 3 de noviembre, por el que se adoptan medidas urgentes de apoyo a entidades del Tercer Sector de Acci\u00f3n Social de \u00e1mbito estatal.<\/li>\n<li>Real Decreto-ley 35\/2020, de 22 de diciembre, de medidas urgentes de apoyo al sector tur\u00edstico, la hosteler\u00eda y el comercio y en materia tributaria.<\/li>\n<li>Real Decreto-ley 37\/2020, de 22 de diciembre, de medidas urgentes para hacer frente a las situaciones de vulnerabilidad social y econ\u00f3mica en el \u00e1mbito de la vivienda y en materia de transportes.<\/li>\n<li>Real Decreto-ley 38\/2020, de 29 de diciembre, por el que se adoptan medidas de adaptaci\u00f3n a la situaci\u00f3n de Estado tercero del Reino Unido de Gran Breta\u00f1a e Irlanda del Norte tras la finalizaci\u00f3n del periodo transitorio previsto en el Acuerdo sobre la retirada del Reino Unido de Gran Breta\u00f1a e Irlanda del Norte de la Uni\u00f3n Europea y de la Comunidad Europea de la Energ\u00eda At\u00f3mica, de 31 de enero de 2020.<\/li>\n<li>Real Decreto-ley 39\/2020, de 29 de diciembre, de medidas financieras de apoyo social y econ\u00f3mico y de cumplimiento de la ejecuci\u00f3n de sentencias.<\/li>\n<li>Real Decreto-ley 36\/2020, de 30 de diciembre, por el que se aprueban medidas urgentes para la modernizaci\u00f3n de la Administraci\u00f3n P\u00fablica y para la ejecuci\u00f3n del Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>DECRETOS LEYES ARAG\u00d3N<\/h3>\n<p>&nbsp;<\/p>\n<ul>\n<li>Decreto-ley 3\/2020, de 3 de junio, del Gobierno de Arag\u00f3n, por el que se autoriza la tramitaci\u00f3n, por el procedimiento de concesi\u00f3n directa, de determinadas subvenciones para la financiaci\u00f3n de proyectos de investigaci\u00f3n sobre el SARS-COV-2 y la enfermedad COVID-19.<\/li>\n<li>Decreto-ley 5\/2020, de 29 de junio, del Gobierno de Arag\u00f3n, por el que se regula la Prestaci\u00f3n Aragonesa Complementaria del Ingreso M\u00ednimo Vital y el Servicio P\u00fablico Aragon\u00e9s de Inclusi\u00f3n Social.<\/li>\n<li>Decreto-ley 6\/2020, de 30 de julio, del Gobierno de Arag\u00f3n, por el que se autoriza la tramitaci\u00f3n, por el procedimiento de concesi\u00f3n directa, de determinadas subvenciones del Departamento de Sanidad, como refuerzo de la estrategia de prevenci\u00f3n y control de la pandemia COVID-19 en la Comunidad Aut\u00f3noma de Arag\u00f3n.<\/li>\n<li>Decreto-ley 10\/2020, de 11 de noviembre, del Gobierno de Arag\u00f3n, por el que se modifca el Decreto-ley 4\/2020, de 24 de junio, del Gobierno de Arag\u00f3n, por el que se adoptan medidas urgentes y extraordinarias para el impulso de la Estrategia Aragonesa para la Recuperaci\u00f3n Social y Econ\u00f3mica.<\/li>\n<li>Decreto-ley 11\/2020, de 9 de diciembre, del Gobierno de Arag\u00f3n, por el que se modifica el anexo del Decreto-ley 4\/2020, de 24 de junio, del Gobierno de Arag\u00f3n, por el que se adoptan medidas urgentes y extraordinarias para el impulso de la Estrategia Aragonesa para la Recuperaci\u00f3n Social y Econ\u00f3mica.<\/li>\n<li>Decreto-ley 12\/2020, de 9 de diciembre, del Gobierno de Arag\u00f3n, por el que se adoptan medidas urgentes y extraordinarias para el impulso de la Estrategia Aragonesa para la Recuperaci\u00f3n Social y Econ\u00f3mica, en el \u00e1mbito del transporte p\u00fablico regular interurbano de viajeros de uso general por carretera en Arag\u00f3n.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb45&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb css=\u00bb.vc_custom_1610018044125{margin-right: 5px !important;margin-left: 5px !important;}\u00bb][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb10&#8243;][vc_single_image image=\u00bb28&#8243; img_size=\u00bb\u00bb onclick=\u00bbcustom_link\u00bb qode_css_animation=\u00bb\u00bb link=\u00bbhttp:\/\/memoria.cepymearagon.es\/index.php\/2020-2\/\u00bb][\/vc_column][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb30&#8243;][custom_font font_size=\u00bb15&#8243; line_height=\u00bb26&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb300&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbno\u00bb border_color=\u00bb#114733&#8243;] Nuestra organizaci\u00f3n [\/custom_font][\/vc_column][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb30&#8243;][custom_font font_size=\u00bb15&#8243; line_height=\u00bb26&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb300&#8243; text_decoration=\u00bbnone\u00bb text_shadow=\u00bbno\u00bb border_color=\u00bb#114733&#8243;] Nuestros servicios [\/custom_font][\/vc_column][vc_column width=\u00bb1\/6&#8243;][vc_empty_space height=\u00bb30&#8243;][custom_font font_size=\u00bb15&#8243; line_height=\u00bb26&#8243; font_style=\u00bbnormal\u00bb text_align=\u00bbleft\u00bb font_weight=\u00bb300&#8243; text_decoration=\u00bbnone\u00bb [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"landing_page.php","meta":{"footnotes":""},"class_list":["post-2249","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/pages\/2249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/comments?post=2249"}],"version-history":[{"count":6,"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/pages\/2249\/revisions"}],"predecessor-version":[{"id":2476,"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/pages\/2249\/revisions\/2476"}],"wp:attachment":[{"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/media?parent=2249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}