{"id":1173,"date":"2019-03-27T13:01:45","date_gmt":"2019-03-27T13:01:45","guid":{"rendered":"http:\/\/memoria.cepymearagon.es\/?page_id=1173"},"modified":"2019-03-27T14:24:28","modified_gmt":"2019-03-27T14:24:28","slug":"civil-mercantil","status":"publish","type":"page","link":"https:\/\/memoria.cepymearagon.es\/index.php\/civil-mercantil\/","title":{"rendered":"Civil Mercantil"},"content":{"rendered":"<p>[vc_row css_animation=\u00bbelement_from_bottom\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][vc_empty_space][icon_text box_type=\u00bbicon_in_a_box\u00bb icon_type=\u00bbnormal\u00bb icon_size=\u00bbfa-lg\u00bb use_custom_icon_size=\u00bbno\u00bb title=\u00bbASESOR\u00cdA CIVIL MERCANTIL\u00bb title_tag=\u00bbh2&#8243; separator=\u00bbno\u00bb][vc_empty_space height=\u00bb48&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bbelement_from_bottom\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column width=\u00bb1\/2&#8243;][qode_in_device_slider device=\u00bbdesktop\u00bb titles_on_hover=\u00bbno\u00bb navigation=\u00bbno\u00bb auto_start=\u00bbyes\u00bb][qode_in_device_slider_item target=\u00bb_self\u00bb image=\u00bb1178&#8243;][\/qode_in_device_slider][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_tabs style=\u00bbboxed\u00bb][vc_tab title=\u00bbDescripci\u00f3n\u00bb tab_id=\u00bb1552574792928-2-21658-e7ab\u00bb][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Al igual que en anteriores ejercicios, y en cumplimiento del contenido y compromisos de la Carta de Servicios, la Asesor\u00eda Jur\u00eddica ha venido desarrollando en el a\u00f1o 2018 las funciones habituales de informaci\u00f3n, asistencia y asesoramiento en las \u00e1reas que le son propias, a solicitud de las empresas asociadas y sus componentes, bien de forma individual o colectiva.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbServicios\u00bb tab_id=\u00bb2450ae19-cb59-41658-e7ab\u00bb][vc_empty_space height=\u00bb30&#8243;][vc_column_text]En concreto, se han seguido realizado las siguientes prestaciones de servicios:[\/vc_column_text][vc_empty_space height=\u00bb10&#8243;][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbInformaci\u00f3n legislativa, con notificaci\u00f3n de las novedades normativas con trascendencia en \u00e1reas civil, mercantil, fiscal y administrativa, tanto en el \u00e1mbito interno de FEMZ como a sus asociados\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbEmisi\u00f3n de dict\u00e1menes e informes, sobre novedades legislativas o materias de inter\u00e9s para los asociados\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbFormulaci\u00f3n de observaciones y alegaciones ante la Administraci\u00f3n en relaci\u00f3n a proyectos normativos\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbParticipaci\u00f3n, como componentes, en Tribunales auton\u00f3micos y locales de consumo, mediaci\u00f3n y arbitraje\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbParticipaci\u00f3n, como componentes, en Organismos del Gobierno de Arag\u00f3n (Comisi\u00f3n de Precios, Consejo del Consumo, Junta Consultiva de Contrataci\u00f3n Administrativa, Foro de la contrataci\u00f3n, etc.)\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbAsistencia y participaci\u00f3n en convocatorias, foros y reuniones p\u00fablicas convocadas por la Administraci\u00f3n (consumo, etc.)\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbAsesoramiento en materia contractual: informaci\u00f3n y asesoramiento en relaciones mercantiles de todo tipo, redacci\u00f3n de contratos y convenios, y constituci\u00f3n, modificaci\u00f3n y disoluci\u00f3n de entidades y sociedades mercantiles\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbInformaci\u00f3n y asesoramiento en aspectos jur\u00eddicos relevantes para la puesta en marcha, alta y legalizaci\u00f3n de actividades empresariales\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbFormulaci\u00f3n e impugnaci\u00f3n de recursos y sanciones administrativas\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbResoluci\u00f3n, por v\u00eda transaccional o judicial, de reclamaciones de cantidad, aplicaci\u00f3n o interpretaci\u00f3n contractual o reclamaci\u00f3n en materia de garant\u00edas o de consumo\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbInformaci\u00f3n sobre gestiones de \u00edndole personal, como herencias, capitulaciones matrimoniales, etc.\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbConsultas verbales, telef\u00f3nicas, por correo electr\u00f3nico y presenciales\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tab][\/vc_tabs][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb100&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bbelement_from_bottom\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][icon_text box_type=\u00bbicon_in_a_box\u00bb icon_type=\u00bbnormal\u00bb icon_size=\u00bbfa-lg\u00bb use_custom_icon_size=\u00bbno\u00bb title=\u00bbMaterias destacadas\u00bb title_tag=\u00bbh2&#8243; separator=\u00bbno\u00bb][vc_empty_space height=\u00bb48&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bbelement_from_bottom\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column width=\u00bb1\/2&#8243;][vc_tabs style=\u00bbboxed\u00bb][vc_tab title=\u00bbReclamaciones de cantidad por impago\u00bb tab_id=\u00bb1552574792928-2-21658-e7ab\u00bb][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Si bien sigue constituyendo una de las consultas habituales, se ha detenido el aumento constatado en el anterior ejercicio, disminuyendo la solicitud de informaci\u00f3n y modelos para el planteamiento del procedimiento judicial Monitorio de reclamaci\u00f3n de cantidad.<\/p>\n<p>&nbsp;<\/p>\n<p>Como se destaca todos los a\u00f1os, la actuaci\u00f3n en este \u00e1mbito de reclamaciones es doble: buscar soluci\u00f3n al puntual incumplimiento contractual por parte del acreedor, as\u00ed como animar a las distintas Asociaciones y sus componentes a adoptar h\u00e1bitos y protocolos de actuaci\u00f3n que favorezcan el cobro de tales cantidades y el cumplimiento de las obligaciones contractuales en general (redacci\u00f3n de contratos y presupuestos, justificaci\u00f3n documental de las intervenciones o actuaciones con los clientes, etc.) y es que, pese a la insistencia en tal tema, sigue siendo frecuente el comprobar que, ante situaciones de morosidad o impago, no se posee m\u00e1s documentaci\u00f3n acreditativa de la obra o servicio realizados que las facturas emitidas por el asociado, con la problem\u00e1tica que implica tal falta de prueba en reclamaciones judiciales o extrajudiciales.<\/p>\n<p>&nbsp;<\/p>\n<p>El porcentaje de \u00e9xito de acuerdos y transacciones extrajudiciales en reclamaci\u00f3n de cantidad es, lamentablemente escaso, por lo que se han promocionado entre los asociados formulas lo menos gravosas posibles para la reclamaci\u00f3n judicial de deudas. En este sentido se promueve y facilita entre asociaciones y asociados informaci\u00f3n y modelos de reclamaci\u00f3n judicial mediante el Procedimiento Monitorio.<\/p>\n<p>&nbsp;<\/p>\n<p>Las renegociaciones de cr\u00e9ditos y documentaci\u00f3n (reconocimientos) de deudas siguen siendo, como consecuencia de lo anteriormente expuesto, una materia de consulta habitual en la Asesor\u00eda[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbConcursos de acreedores\u00bb tab_id=\u00bb2450ae19-cb59-41658-e7ab\u00bb][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Continuando la din\u00e1mica ya puesta de manifiesto en el anterior ejercicio, han disminuido dr\u00e1sticamente los expedientes de concurso judicial de acreedores, si bien se siguen planteando dudas sobre ejecuciones y cumplimientos de convenios de concursos de anteriores ejercicios.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbAcceso a pr\u00e9stamos y l\u00edneas de financiaci\u00f3n\u00bb tab_id=\u00bb1552575067425-2-31658-e7ab\u00bb][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Al igual que anteriores ejercicios se mantiene el supuesto habitual (en aut\u00f3nomos y micropymes) del caso de conversi\u00f3n de las l\u00edneas de cr\u00e9dito \u2013 a la hora de su renovaci\u00f3n &#8211; en pr\u00e9stamos personales con exigencia de gran n\u00famero de garant\u00edas o afianzamientos personales.<\/p>\n<p>&nbsp;<\/p>\n<p>Sin embargo, se nos traslada por los asociados la sensaci\u00f3n de una mayor facilidad de acceso al cr\u00e9dito en general.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbGarant\u00edas del consumidor\u00bb tab_id=\u00bb1553695143046-3-7&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]No constituye novedad y se reitera como una de las materias fundamentales en la Asesor\u00eda ejercicio tras ejercicio, en especial lo referente a contenido y plazo de las mismas.<\/p>\n<p>&nbsp;<\/p>\n<p>Se reitera la obligaci\u00f3n legal de tenencia de Hojas de reclamaciones a disposici\u00f3n de los consumidores, en especial en actividades con atenci\u00f3n directa al p\u00fablico, recordando la necesidad de emplear el nuevo modelo existente, haciendo notar que el mismo incluye la opci\u00f3n de sumisi\u00f3n voluntaria a arbitraje.<\/p>\n<p>&nbsp;<\/p>\n<p>Como en otros ejercicios, por el Consejo Aragon\u00e9s de Consumo, y dada nuestra condici\u00f3n de vocales \u2013\u00a0 a trav\u00e9s de CEPYME &#8211; en tal instituci\u00f3n, se ha informado de las campa\u00f1as de inspecci\u00f3n en materia de Consumo han promovido, tanto en \u00e1mbito nacional como auton\u00f3mico, las autoridades de consumo, habi\u00e9ndose prestado colaboraci\u00f3n en labores de difusi\u00f3n de las mismas por medio de notificaci\u00f3n al efecto (circulares) a los Asociados.<\/p>\n<p>&nbsp;<\/p>\n<p>Se destacan \u2013 por habituales \u2013 las campa\u00f1as generales de rebajas, precios, contrataci\u00f3n, etc. As\u00ed como las sectoriales (talleres, centros de est\u00e9tica, servicios financieros, etc). Ha sido la actividad de centros dentales (I Dental, etc) la que ha centrado gran parte de los esfuerzos y medios de la Direcci\u00f3n General de Consumo en fechas recientes.<\/p>\n<p>&nbsp;<\/p>\n<p>Al igual que indic\u00e1bamos en la Memoria del pasado ejercicio, siguen realiz\u00e1ndose intervenciones ante el Tribunal Arbitral de Consumo, como vocal \/ componente en representaci\u00f3n de las organizaciones empresariales. La intervenci\u00f3n ha descendido respecto a otros a\u00f1os dada la realizaci\u00f3n de convenios directos de las Asociaciones con el organismo de Consumo y que se traduce en la posibilidad de designaci\u00f3n de \u00e1rbitros por las mismas, haciendo menos necesaria la intervenci\u00f3n de la Federaci\u00f3n. Es esta sede los temas fundamentalmente dilucidados y que afectan con frecuencia a asociados, se refieren a las siguientes materias (por orden de incidencia):[\/vc_column_text][vc_empty_space height=\u00bb10&#8243;][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbTelefon\u00eda\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbServicios de suministro el\u00e9ctrico: facturaci\u00f3n y contrataci\u00f3n\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbGarant\u00edas de ventas de bienes al consumo: especialmente electrodom\u00e9sticos y ropa y vestidos\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbReparaciones: electrodom\u00e9sticos, aparatos de telefon\u00eda y el\u00e9ctricos en general, as\u00ed como talleres de autom\u00f3vil\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbObras y servicios y reparaciones a domicilio: fontaner\u00eda, electricidad y otros\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbVenta de muebles\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb10&#8243;][vc_column_text]Se promueve el empleo de f\u00f3rmulas contractuales de sumisi\u00f3n al arbitraje para la resoluci\u00f3n de conflictos de interpretaci\u00f3n y\/o aplicaci\u00f3n de las relaciones comerciales, habi\u00e9ndose comprobado igualmente no solo un incremento del n\u00famero de asuntos, sino tambi\u00e9n de la entidad econ\u00f3mica y jur\u00eddica de los mismos.<\/p>\n<p>&nbsp;<\/p>\n<p>Se ha continuado en la l\u00ednea de fomentar la participaci\u00f3n directa de las Asociaciones en la labor arbitral, mediante la suscripci\u00f3n de nuevos convenios de adhesi\u00f3n a las f\u00f3rmulas de arbitraje con designaci\u00f3n simult\u00e1nea de \u00e1rbitros por las propias asociaciones. El proceso \u2013 con entrega de distintivos al efecto y campa\u00f1a p\u00fablica por las autoridades de consumo \u2013 se mantiene al igual que en ejercicios anteriores.<\/p>\n<p>&nbsp;<\/p>\n<p>Como datos estad\u00edsticos, y tal y como se hace constar en la informaci\u00f3n institucional de Consumo, el porcentaje de laudos favorables a los empresarios se sigue situando en una cifra media cercana (ligeramente inferior) al 50% de los emitidos, y de los mismos sigue desprendi\u00e9ndose normalmente la necesidad de recordar a los Asociados la necesidad de cumplir con la correcta y adecuada documentaci\u00f3n de las relaciones comerciales con los consumidores (contratos, presupuestos, etc.).<\/p>\n<p>&nbsp;<\/p>\n<p>Como aspecto negativo, se encuentra la sensaci\u00f3n, extendida en algunos sectores empresariales, de que las facilidad y gratuidad de los servicios de arbitraje de consumo pudiera promover en ocasiones la querulancia y uso abusivo de los mismos por los consumidores como f\u00f3rmula de obtenci\u00f3n de ventajas o beneficios en detrimento del empresario. Desde la Asesor\u00eda, se atienden y controlan los posibles casos.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbContrataci\u00f3n con la Administraci\u00f3n\u00bb tab_id=\u00bb1553695358573-4-5&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Relacionado con esta materia, han sido frecuentes las gestiones y consultas en materias accesorias, como la del registro de subcontrataci\u00f3n y la inscripci\u00f3n de empresas licitantes en los registros p\u00fablicos al efecto, as\u00ed como las garant\u00edas de cobro por el subcontratado y la posibilidad del ejercicio de la acci\u00f3n directa contra la administraci\u00f3n en caso de impago del contratista.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s de esas materias \u2013 habituales \u2013 se a\u00f1ade este ejercicio las posibles discordancias propias de la practica derivada de la entrada en vigor de la nueva normativa de contrataci\u00f3n p\u00fablica (<u>Ley 9\/2017, de 8 de noviembre, de Contratos del Sector P\u00fablico<\/u>), en especial las derivadas de los contratos de menor entidad, reflejo del nuevo criterio legal de priorizaci\u00f3n en la formaci\u00f3n de lotes contractuales para permitir el acceso a Pymes: calificaci\u00f3n o no de los licitantes, pliegos con exigencias t\u00e9cnicas o de producto determinado, problemas de valoraci\u00f3n por el abandono del criterio del precio, etc.<\/p>\n<p>&nbsp;<\/p>\n<p>Como en otros a\u00f1os se recuerda, por lo que de acceso a informaci\u00f3n de alto nivel y v\u00eda de planteamiento de consultas supone para las Asociaciones, la participaci\u00f3n de CEPYME\u00a0 en la <u>Junta Consultiva de Contrataci\u00f3n Administrativa de Arag\u00f3n<\/u>: CEPYME Arag\u00f3n lleva ya tiempo participando en este organismo, pero debe recordarse nuevamente \u2013 en especial tras las \u00faltimas novedades legislativas habidas en el tema de contrataci\u00f3n p\u00fablica \u2013 que parte de la problem\u00e1tica habitual de la contrataci\u00f3n (conflictos interpretativos o de aplicaci\u00f3n o pliegos o contratos p\u00fablicos, reclamaciones o consultas) pueden tener un cauce de soluci\u00f3n a trav\u00e9s de la solicitud de informes o recomendaciones a la citada Junta Consultiva o, mediante el planteamiento de recursos ante el Tribunal Administrativo de Contratos P\u00fablicos de Arag\u00f3n. (TAPCA \u2013 Recurso especial en materia de contrataci\u00f3n)<\/p>\n<p>&nbsp;<\/p>\n<p>Como novedad, desde su constituci\u00f3n el 19 de septiembre de 2017, se participa igualmente en el <u>Foro de Contratos P\u00fablicos de la CA de Arag\u00f3n<\/u>, creado para complementar a la Junta Consultiva y con la intenci\u00f3n de ejercer foro de debate y recepci\u00f3n de los intereses de los distintos agentes sociales y la administraci\u00f3n en el uso de la herramienta de planificaci\u00f3n econ\u00f3mica que constituye la contrataci\u00f3n p\u00fablica en general. No es tanto un \u00f3rgano de car\u00e1cter t\u00e9cnico sino de comunicaci\u00f3n e intercambio de los intereses de los agentes que participan en la contrataci\u00f3n, todo ello en l\u00ednea de la nueva legislaci\u00f3n sobre la materia.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbAsociaciones\u00bb tab_id=\u00bb1553695512227-5-4&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Sigue prest\u00e1ndose colaboraci\u00f3n a las mismas, habi\u00e9ndose reducido significativamente la l\u00ednea de creaci\u00f3n de nuevas asociaciones (consultas en tal sentido) habidas en ejercicios anteriores.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbProtecci\u00f3n de Datos de car\u00e1cter Personal\u00bb tab_id=\u00bb1553695540941-6-4&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Se siguen planteado consultas al efecto, muchas veces motivadas por campa\u00f1as de marketing muy agresivas llevadas a cabo por empresas dedicadas a prestar servicios en tal materia y que motivan dudas en los asociados.<\/p>\n<p>&nbsp;<\/p>\n<p>Se insiste en la importancia del cumplimiento de esta normativa, con advertencia de las sanciones previstas para el caso de incumplimiento y la peligrosidad que supone el no cumplimiento de los \u2013 sencillos \u2013 tr\u00e1mites legales previstos,<\/p>\n<p>&nbsp;<\/p>\n<p>Se mantienen las consultas de los Asociados sobre los tr\u00e1mites y gestiones necesarias para el alta y registro de las bases de datos de car\u00e1cter personal, inform\u00e1ndose de la posibilidad de realizar tal gesti\u00f3n telem\u00e1ticamente ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos de Car\u00e1cter Personal.<\/p>\n<p>&nbsp;<\/p>\n<p>Se mantienen las consultas sobre los llamados \u201clistados de morosidad\u201d, habi\u00e9ndose recordado en varias ocasiones las limitaciones legales para su uso, tanto por la normativa de protecci\u00f3n de la competencia, como por la propia de datos de car\u00e1cter personal.<\/p>\n<p>&nbsp;<\/p>\n<p>La novedad este ejercicio vino marcada por la entrada en vigor del <u>Reglamento General de Protecci\u00f3n de Datos (RGPD)<\/u>, as\u00ed como la publicaci\u00f3n posterior de la nueva <u>Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales<\/u> y garant\u00eda de los derechos digitales que ha exigido a las empresas \u2013 en un proceso que continua en la actualidad \u2013 un necesario proceso de adaptaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Se ha promocionado el uso de la herramienta inform\u00e1tica FACILITA, que se encuentra en la p\u00e1gina web de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, para realizar el alta y dar cumplimiento a gran parte de las exigencias legales en tal materia para PYMES y aut\u00f3nomos, habi\u00e9ndose realizado un elevado n\u00famero de charlas, exposiciones y jornadas en asociaciones (no solo de la FEMZ y en Zaragoza, sino en otras localidades), explicando el contenido de la reforma.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbSupuestos de transmisi\u00f3n y\/o sucesi\u00f3n\u00bb tab_id=\u00bb1553695598661-7-6&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Se siguen planteando gran n\u00famero de peticiones de intervenci\u00f3n de esta Asesor\u00eda (derivadas en ocasiones al \u00e1rea de la Asesor\u00eda Laboral) para <u>supuestos de transmisi\u00f3n y\/o sucesi\u00f3n de peque\u00f1as empresas<\/u>, de car\u00e1cter familiar, tanto a familiares, como a empleados o terceros, con ramificaciones en los temas fiscales, laborales (sucesi\u00f3n de plantillas, etc).<\/p>\n<p>&nbsp;<\/p>\n<p>Muchas de las consultas se deben a las manifiestas dificultades de las empresas de mantener la actividad dentro de umbrales de rentabilidad admisibles, que llevan a provocar el adelantamiento de las situaciones de cierre o jubilaci\u00f3n. Muchas de las consultas han venido motivadas, a su vez, por el cambio de la normativa laboral en materia de jubilaci\u00f3n o prolongaci\u00f3n de la vida laboral (Real Decreto-ley 5\/2013, de 15 de marzo, de medidas para favorecer la continuidad de la vida laboral de los trabajadores de mayor edad y promover el envejecimiento activo, o la Ley 6\/2017, de 24 de octubre, de Reformas Urgentes del Trabajo Aut\u00f3nomo, por ejemplo).[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbCampa\u00f1as de inspecci\u00f3n de la Administraci\u00f3n\u00bb tab_id=\u00bb1553695653522-8-9&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Adem\u00e1s de las habituales (y anunciadas con antelaci\u00f3n) campa\u00f1as de Consumo (y de las de car\u00e1cter fiscal que se detallar\u00e1n en informe aparte) se han constatado requerimientos de la Administraci\u00f3n en materias tales como:[\/vc_column_text][vc_empty_space height=\u00bb10&#8243;][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbRegistro de empresas \/ actividades comerciales\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbRevisi\u00f3n de instalaciones el\u00e9ctricas (de \u201cbaja\u201d, y ascensores)\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][icon_list_item icon=\u00bbfa-check\u00bb icon_type=\u00bbtransparent\u00bb title=\u00bbDep\u00f3sitos de fianzas de arrendamientos\u00bb icon_color=\u00bb#cad327&#8243; title_color=\u00bb#898989&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tab][vc_tab title=\u00bbMedidas de orden social\u00bb tab_id=\u00bb1553695782076-9-1&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Se hace referencia a esta materia \u2013 al igual que en ejercicios anteriores &#8211; por lo que de llamativo tiene la escasa repercusi\u00f3n en lo que a consultas o intervenciones de esta Asesoria ha tenido una norma (Ley 25\/2015, de 28 de julio) de especial trascendencia en situaciones de iliquidez o insolvencia. El escaso uso de tal herramienta legal, viene pareja al descenso de situaciones de concurso.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbReclamaciones entidades financieras\u00bb tab_id=\u00bb1553695823767-10-9&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Siguen siendo habituales las consultas realizadas en esta materia, motivadas por las noticias y campa\u00f1as informativas de asociaciones de consumidores al efecto.<\/p>\n<p>&nbsp;<\/p>\n<p>Se constata que las sentencias habidas en tal materia hacen m\u00e1s f\u00e1ciles los acuerdos transaccionales con las entidades bancarias.[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbAdministraci\u00f3n Electr\u00f3nica\u00bb tab_id=\u00bb1553695870497-11-5&#8243;][vc_empty_space height=\u00bb30&#8243;][vc_column_text]La nueva Ley L 39\/2015, de procedimiento administrativo com\u00fan y la L 40\/2015, de r\u00e9gimen jur\u00eddico del sector p\u00fablico, y su entrada en vigor el 1 de octubre del 2016 han supuesto \u2013 y as\u00ed se ha informado y contestado a diversas consultas sobre el tema \u2013 una peque\u00f1a revoluci\u00f3n en la relaci\u00f3n de las empresas (en especial las que adoptan formas de persona jur\u00eddica) con la imposici\u00f3n de la forma de comunicaci\u00f3n electr\u00f3nica como \u00fanica posible con las AAPP, adem\u00e1s de otras novedades de gran calado (registro de apoderamientos, etc)<\/p>\n<p>&nbsp;<\/p>\n<p>Durante el a\u00f1o 2018 (al igual que en el 2017) se ha reiterado constantemente entre los asociados, y no \u00fanicamente entre los asociados personas jur\u00eddicas (\u00fanicos obligados de momento), la importancia de no quedar rezagados en tal materia, evitando en lo posible la llamada \u201cbrecha digital\u201d en la relaci\u00f3n con las Administraci\u00f3n y con otras entidades.[\/vc_column_text][\/vc_tab][\/vc_tabs][\/vc_column][vc_column width=\u00bb1\/2&#8243;][qode_in_device_slider device=\u00bbtablet-portrait\u00bb titles_on_hover=\u00bbno\u00bb navigation=\u00bbno\u00bb auto_start=\u00bbyes\u00bb][qode_in_device_slider_item target=\u00bb_self\u00bb image=\u00bb1180&#8243;][\/qode_in_device_slider][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb100&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bbelement_from_bottom\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][icon_text box_type=\u00bbicon_in_a_box\u00bb icon_type=\u00bbnormal\u00bb icon_size=\u00bbfa-lg\u00bb use_custom_icon_size=\u00bbno\u00bb title=\u00bbNormativa destacada\u00bb title_tag=\u00bbh2&#8243; separator=\u00bbno\u00bb][vc_empty_space height=\u00bb48&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bbelement_from_bottom\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column width=\u00bb1\/2&#8243;][vc_empty_space height=\u00bb80&#8243;][qode_in_device_slider device=\u00bbphone-landscape\u00bb titles_on_hover=\u00bbno\u00bb navigation=\u00bbno\u00bb auto_start=\u00bbyes\u00bb][qode_in_device_slider_item target=\u00bb_self\u00bb image=\u00bb1181&#8243;][\/qode_in_device_slider][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_tabs style=\u00bbboxed\u00bb][vc_tab title=\u00bbNormativa nacional\u00bb tab_id=\u00bb1552574792928-2-21658-e7ab\u00bb][vc_empty_space height=\u00bb30&#8243;][vc_column_text]<\/p>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-16672\">Ley Org\u00e1nica 2\/2018, de 5 de diciembre, para la modificaci\u00f3n de la Ley Org\u00e1nica 5\/1985, de 19 de junio, del R\u00e9gimen Electoral General para garantizar el derecho de sufragio de todas las personas con discapacidad.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-16673\">Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales<\/a>.<\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-17987\">Ley Org\u00e1nica 4\/2018, de 28 de diciembre, de reforma de la Ley Org\u00e1nica 6\/1985, de 1 de julio, del Poder Judicial.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-17988\">Ley Org\u00e1nica 5\/2018, de 28 de diciembre, de reforma de la Ley Org\u00e1nica 6\/1985, de 1 de julio, del Poder Judicial, sobre medidas urgentes en aplicaci\u00f3n del Pacto de Estado en materia de violencia de g\u00e9nero.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-9268\">Ley 6\/2018, de 3 de julio, de Presupuestos Generales del Estado para el a\u00f1o 2018<\/a>.<\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-7832\">Ley 4\/2018, de 11 de junio, por la que se modifica el texto refundido de la Ley General para la Defensa de los Consumidores y Usuarios y otras leyes complementarias, aprobado por Real Decreto Legislativo 1\/2007, de 16 de noviembre<\/a>.<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-7833\">Ley 5\/2018, de 11 de junio, de modificaci\u00f3n de la Ley 1\/2000, de 7 de enero, de Enjuiciamiento Civil, en relaci\u00f3n a la ocupaci\u00f3n ilegal de viviendas<\/a>.<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-10240\">Ley 7\/2018, de 20 de julio, de modificaci\u00f3n de la Ley 42\/2007, de 13 de diciembre, del Patrimonio Natural y de la Biodiversidad.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-16674\">Ley 9\/2018, de 5 de diciembre, por la que se modifica la Ley 21\/2013, de 9 de diciembre, de evaluaci\u00f3n ambiental, la Ley 21\/2015, de 20 de julio, por la que se modifica la Ley 43\/2003, de 21 de noviembre, de Montes y la Ley 1\/2005, de 9 de marzo, por la que se regula el r\u00e9gimen del comercio de derechos de emisi\u00f3n de gases de efecto invernadero<\/a>.<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-17989\">Ley 11\/2018, de 28 de diciembre, por la que se modifica el C\u00f3digo de Comercio, el texto refundido de la Ley de Sociedades de Capital aprobado por el Real Decreto Legislativo 1\/2010, de 2 de julio, y la Ley 22\/2015, de 20 de julio, de Auditor\u00eda de Cuentas, en materia de informaci\u00f3n no financiera y diversidad.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-13180\">Real Decreto-ley 14\/2018, de 28 de septiembre, por el que se modifica el texto refundido de la Ley del Mercado de Valores, aprobado por el Real Decreto Legislativo 4\/2015, de 23 de octubre.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-17992\">Real Decreto-ley 28\/2018, de 28 de diciembre, para la revalorizaci\u00f3n de las pensiones p\u00fablicas y otras medidas urgentes en materia social, laboral y de empleo.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-5059\">Real Decreto-ley 2\/2018, de 13 de abril, por el que se modifica el texto refundido de la Ley de Propiedad Intelectual, aprobado por el Real Decreto Legislativo 1\/1996, de 12 de abril, y por el que se incorporan al ordenamiento jur\u00eddico espa\u00f1ol la Directiva 2014\/26\/UE del Parlamento Europeo y del Consejo, de 26 de febrero de 2014, y la Directiva (UE) 2017\/1564 del Parlamento Europeo y del Consejo, de 13 de septiembre de 2017.<\/a>\u00a0\u2013 Disposici\u00f3n derogada<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-5451\">Real Decreto-ley 3\/2018, de 20 de abril, por el que se modifica la Ley 16\/1987, de 30 de julio, de Ordenaci\u00f3n de los Transportes Terrestres, en materia de arrendamiento de veh\u00edculos con conductor.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-10751\">Real Decreto-ley 5\/2018, de 27 de julio, de medidas urgentes para la adaptaci\u00f3n del Derecho espa\u00f1ol a la normativa de la Uni\u00f3n Europea en materia de protecci\u00f3n de datos.\u00a0<\/a>\u00a0\u2013 Disposici\u00f3n derogada<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-10752\">Real Decreto-ley 7\/2018, de 27 de julio, sobre el acceso universal al Sistema Nacional de Salud.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-11134\">Real Decreto-ley 8\/2018, de 3 de agosto, por el que se modifica el Real Decreto-ley 16\/2014, de 19 de diciembre, por el que se regula el Programa de Activaci\u00f3n para el Empleo.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-11135\">Real Decreto-ley 9\/2018, de 3 de agosto, de medidas urgentes para el desarrollo del Pacto de Estado contra la violencia de g\u00e9nero.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-12131\">Real Decreto-ley 11\/2018, de 31 de agosto, de transposici\u00f3n de directivas en materia de protecci\u00f3n de los compromisos por pensiones con los trabajadores, prevenci\u00f3n del blanqueo de capitales y requisitos de entrada y residencia de nacionales de pa\u00edses terceros y por el que se modifica la Ley 39\/2015, de 1 de octubre, del Procedimiento Administrativo Com\u00fan de las Administraciones P\u00fablicas<\/a>.<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-12257\">Real Decreto-ley 12\/2018, de 7 de septiembre, de seguridad de las redes y sistemas de informaci\u00f3n.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-13179\">Real Decreto-ley 13\/2018, de 28 de septiembre, por el que se modifica la Ley 16\/1987, de 30 de julio, de Ordenaci\u00f3n de los Transportes Terrestres, en materia de arrendamiento de veh\u00edculos con conductor.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-13593\">Real Decreto-ley 15\/2018, de 5 de octubre, de medidas urgentes para la transici\u00f3n energ\u00e9tica y la protecci\u00f3n de los consumidores.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-15344\">Real Decreto-ley 17\/2018, de 8 de noviembre, por el que se modifica el Texto refundido de la Ley del Impuesto sobre Transmisiones Patrimoniales y Actos Jur\u00eddicos Documentados, aprobado por el Real Decreto Legislativo 1\/1993, de 24 de septiembre.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-15345\">Real Decreto-ley 18\/2018, de 8 de noviembre, sobre medidas urgentes en materia de carreteras.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-16036\">Real Decreto-ley 19\/2018, de 23 de noviembre, de servicios de pago y otras medidas urgentes en materia financiera.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-16791\">Real Decreto-ley 20\/2018, de 7 de diciembre, de medidas urgentes para el impulso de la competitividad econ\u00f3mica en el sector de la industria y el comercio en Espa\u00f1a.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-17293\">Real Decreto-ley 21\/2018, de 14 de diciembre, de medidas urgentes en materia de vivienda y alquiler.<\/a>\u00a0\u2013 Disposici\u00f3n derogada<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-17599\">Real Decreto-ley 25\/2018, de 21 de diciembre, de medidas urgentes para una transici\u00f3n justa de la miner\u00eda del carb\u00f3n y el desarrollo sostenible de las comarcas mineras.<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-17769\">Real Decreto-ley 23\/2018, de 21 de diciembre, de transposici\u00f3n de directivas en materia de marcas, transporte ferroviario y viajes combinados y servicios de viaje vinculados.\u00a0<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-17991\">Real Decreto-ley 27\/2018, de 28 de diciembre, por el que se adoptan determinadas medidas en materia tributaria y catastral.<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tab][vc_tab title=\u00bbNormativa auton\u00f3mica\u00bb tab_id=\u00bb2450ae19-cb59-41658-e7ab\u00bb][vc_empty_space height=\u00bb30&#8243;][vc_column_text]<\/p>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-1683\">Ley 10\/2017, de 30 de noviembre, de r\u00e9gimen especial del municipio de Zaragoza como capital de Arag\u00f3n<\/a>.<\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-5002\">Ley 1\/2018, de 8 de febrero, de di\u00e1logo social y participaci\u00f3n institucional en Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-5003\">Ley 2\/2018, de 28 de febrero, de Presupuestos de la Comunidad Aut\u00f3noma de Arag\u00f3n para el ejercicio 2018.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-7153\">Ley 3\/2018, de 19 de abril, de creaci\u00f3n del Colegio Profesional de Periodistas de Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-7154\">Ley 4\/2018, de 19 de abril, de Identidad y Expresi\u00f3n de G\u00e9nero e Igualdad Social y no Discriminaci\u00f3n de la Comunidad Aut\u00f3noma de Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-7155\">Ley 5\/2018, de 19 de abril, del Taxi.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-11931\">Ley 6\/2018, de 28 de junio, del Voluntariado de Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-11932\">Ley 7\/2018, de 28 de junio, de igualdad de oportunidades entre mujeres y hombres en Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-11933\">Ley 8\/2018, de 28 de junio, de actualizaci\u00f3n de los derechos hist\u00f3ricos de Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-11934\">Ley 9\/2018, de 28 de junio, de modificaci\u00f3n de la ley 8\/2013, de 12 de septiembre, de coordinaci\u00f3n de polic\u00edas locales de Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-14114\">Ley 10\/2018, de 6 de septiembre, de medidas relativas al Impuesto sobre Sucesiones y Donaciones.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-15242\">Ley 11\/2018, de 20 de septiembre, de creaci\u00f3n del Colegio Profesional de Ingenieros en Inform\u00e1tica de Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2018-15243\">Ley 12\/2018, de 20 de septiembre, de creaci\u00f3n del Colegio Profesional de Ingenieros T\u00e9cnicos en Inform\u00e1tica de Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-16531\">Ley 13\/2018, de 4 de octubre, de creaci\u00f3n del Colegio de Economistas de Arag\u00f3n por fusi\u00f3n de los Colegios Oficiales de Economistas de Arag\u00f3n y de Titulados Mercantiles de Arag\u00f3n.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOA-d-2018-90289\">Decreto-ley 1\/2018, de 20 de marzo, de medidas urgentes para la agilizaci\u00f3n, racionalizaci\u00f3n y transparencia de contratos del sector p\u00fablico de peque\u00f1a cuant\u00eda.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOA-d-2018-90392\">Decreto-ley 3\/2018, de 13 de julio, del Gobierno de Arag\u00f3n, sobre tramitaci\u00f3n anticipada de expedientes de gasto dependientes de financiaci\u00f3n externa.<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tab][\/vc_tabs][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb100&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bbelement_from_bottom\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][vc_empty_space][icon_text box_type=\u00bbicon_in_a_box\u00bb icon_type=\u00bbnormal\u00bb icon_size=\u00bbfa-lg\u00bb use_custom_icon_size=\u00bbno\u00bb title=\u00bbASESOR\u00cdA CIVIL MERCANTIL\u00bb title_tag=\u00bbh2&#8243; separator=\u00bbno\u00bb][vc_empty_space height=\u00bb48&#8243;][\/vc_column][\/vc_row][vc_row css_animation=\u00bbelement_from_bottom\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column width=\u00bb1\/2&#8243;][qode_in_device_slider device=\u00bbdesktop\u00bb titles_on_hover=\u00bbno\u00bb navigation=\u00bbno\u00bb auto_start=\u00bbyes\u00bb][qode_in_device_slider_item target=\u00bb_self\u00bb image=\u00bb1178&#8243;][\/qode_in_device_slider][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_tabs style=\u00bbboxed\u00bb][vc_tab title=\u00bbDescripci\u00f3n\u00bb tab_id=\u00bb1552574792928-2-21658-e7ab\u00bb][vc_empty_space height=\u00bb30&#8243;][vc_column_text]Al igual que en anteriores ejercicios, y en cumplimiento del contenido y compromisos de la Carta de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"landing_page.php","meta":{"footnotes":""},"class_list":["post-1173","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/pages\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":5,"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/pages\/1173\/revisions"}],"predecessor-version":[{"id":1182,"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/pages\/1173\/revisions\/1182"}],"wp:attachment":[{"href":"https:\/\/memoria.cepymearagon.es\/index.php\/wp-json\/wp\/v2\/media?parent=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}